{"id":1829,"date":"2021-11-18T23:26:31","date_gmt":"2021-11-18T22:26:31","guid":{"rendered":"https:\/\/www.aggolfe.com\/portefeuille-confidentiel\/"},"modified":"2022-04-26T15:35:09","modified_gmt":"2022-04-26T13:35:09","slug":"confidential-wallet","status":"publish","type":"page","link":"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/","title":{"rendered":"Confidential wallet"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Confidential wallet Entrust us with the search for your property.Some properties have been entrusted to us in all discretion&#8230; From a residence entirely built in local stone and enjoying a splendid view of the Sanguinaires Islands and the open sea, to a sumptuous villa in a highly prized private domain, not to mention a magnificently renovated mansion located in the &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-blank-4.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1829","page","type-page","status-publish","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Confidential wallet - Agence Immobili\u00e8re du Golfe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confidential wallet - Agence Immobili\u00e8re du Golfe\" \/>\n<meta property=\"og:description\" content=\"Confidential wallet Entrust us with the search for your property.Some properties have been entrusted to us in all discretion&#8230; From a residence entirely built in local stone and enjoying a splendid view of the Sanguinaires Islands and the open sea, to a sumptuous villa in a highly prized private domain, not to mention a magnificently renovated mansion located in the ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/\" \/>\n<meta property=\"og:site_name\" content=\"Agence Immobili\u00e8re du Golfe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Aggolfe\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T13:35:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/confidential-wallet\\\/\",\"url\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/confidential-wallet\\\/\",\"name\":\"Confidential wallet - Agence Immobili\u00e8re du Golfe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/#website\"},\"datePublished\":\"2021-11-18T22:26:31+00:00\",\"dateModified\":\"2022-04-26T13:35:09+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/confidential-wallet\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/\",\"name\":\"Agence Immobili\u00e8re du Golfe\",\"description\":\"L\u2019immobilier d&#039;exception en Corse depuis 1994\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/#organization\",\"name\":\"Agence Immobili\u00e8re du Golfe\",\"url\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aggolfe.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Agence-immobiliere-du-golfe_Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.aggolfe.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Agence-immobiliere-du-golfe_Logo.png\",\"width\":257,\"height\":70,\"caption\":\"Agence Immobili\u00e8re du Golfe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aggolfe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Aggolfe\\\/\",\"https:\\\/\\\/www.instagram.com\\\/aggolfe\\\/\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/aggolfe\",\"https:\\\/\\\/www.pinterest.fr\\\/Aggolfe\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Confidential wallet - Agence Immobili\u00e8re du Golfe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/","og_locale":"en_US","og_type":"article","og_title":"Confidential wallet - Agence Immobili\u00e8re du Golfe","og_description":"Confidential wallet Entrust us with the search for your property.Some properties have been entrusted to us in all discretion&#8230; From a residence entirely built in local stone and enjoying a splendid view of the Sanguinaires Islands and the open sea, to a sumptuous villa in a highly prized private domain, not to mention a magnificently renovated mansion located in the ...","og_url":"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/","og_site_name":"Agence Immobili\u00e8re du Golfe","article_publisher":"https:\/\/www.facebook.com\/Aggolfe\/","article_modified_time":"2022-04-26T13:35:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/","url":"https:\/\/www.aggolfe.com\/en\/confidential-wallet\/","name":"Confidential wallet - Agence Immobili\u00e8re du Golfe","isPartOf":{"@id":"https:\/\/www.aggolfe.com\/en\/#website"},"datePublished":"2021-11-18T22:26:31+00:00","dateModified":"2022-04-26T13:35:09+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aggolfe.com\/en\/confidential-wallet\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.aggolfe.com\/en\/#website","url":"https:\/\/www.aggolfe.com\/en\/","name":"Agence Immobili\u00e8re du Golfe","description":"L\u2019immobilier d&#039;exception en Corse depuis 1994","publisher":{"@id":"https:\/\/www.aggolfe.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aggolfe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.aggolfe.com\/en\/#organization","name":"Agence Immobili\u00e8re du Golfe","url":"https:\/\/www.aggolfe.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aggolfe.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.aggolfe.com\/wp-content\/uploads\/2021\/10\/Agence-immobiliere-du-golfe_Logo.png","contentUrl":"https:\/\/www.aggolfe.com\/wp-content\/uploads\/2021\/10\/Agence-immobiliere-du-golfe_Logo.png","width":257,"height":70,"caption":"Agence Immobili\u00e8re du Golfe"},"image":{"@id":"https:\/\/www.aggolfe.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Aggolfe\/","https:\/\/www.instagram.com\/aggolfe\/","https:\/\/fr.linkedin.com\/company\/aggolfe","https:\/\/www.pinterest.fr\/Aggolfe\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/pages\/1829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/comments?post=1829"}],"version-history":[{"count":0,"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/pages\/1829\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aggolfe.com\/en\/wp-json\/wp\/v2\/media?parent=1829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}